{"id":42,"count":1,"description":"","link":"https:\/\/computicslab.in\/blog\/tag\/how-to-install-morpho-l1-in-windows-10\/","name":"how to install morpho l1 in windows 10","slug":"how-to-install-morpho-l1-in-windows-10","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/tags\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/posts?tags=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}