{"id":232,"count":1,"description":"","link":"https:\/\/computicslab.in\/blog\/tag\/how-to-extend-windows-10-update-support\/","name":"how to extend windows 10 update support","slug":"how-to-extend-windows-10-update-support","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/tags\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/posts?tags=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}