{"id":105,"count":1,"description":"","link":"https:\/\/computicslab.in\/blog\/tag\/computics-lab-jp-assist-tool-download\/","name":"computics lab jp assist tool download","slug":"computics-lab-jp-assist-tool-download","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/tags\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/computicslab.in\/blog\/wp-json\/wp\/v2\/posts?tags=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}